{"id":17422,"date":"2023-12-14T05:23:00","date_gmt":"2023-12-14T04:23:00","guid":{"rendered":"https:\/\/www.venalink.es\/spd-horizontal-proyecto-consolidado\/"},"modified":"2023-12-14T05:23:00","modified_gmt":"2023-12-14T04:23:00","slug":"spd-horizontal-proyecto-consolidado","status":"publish","type":"post","link":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/","title":{"rendered":"El SPD Horizontal, un proyecto consolidado"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Desarrollado en 2019 para adaptarse a unas caracter\u00edsticas muy concretas de nuestro mercado, Venalink ha conseguido con el paso del tiempo que el formato Horizontal  se convierta en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-17422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doing-good-by-doing-well-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El SPD Horizontal, un proyecto consolidado - VENALINK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El SPD Horizontal, un proyecto consolidado - VENALINK\" \/>\n<meta property=\"og:description\" content=\"Desarrollado en 2019 para adaptarse a unas caracter\u00edsticas muy concretas de nuestro mercado, Venalink ha conseguido con el paso del tiempo que el formato Horizontal se convierta en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/\" \/>\n<meta property=\"og:site_name\" content=\"VENALINK\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T04:23:00+00:00\" \/>\n<meta name=\"author\" content=\"VENALINK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENALINK\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El SPD Horizontal, un proyecto consolidado - VENALINK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/","og_locale":"ca_ES","og_type":"article","og_title":"El SPD Horizontal, un proyecto consolidado - VENALINK","og_description":"Desarrollado en 2019 para adaptarse a unas caracter\u00edsticas muy concretas de nuestro mercado, Venalink ha conseguido con el paso del tiempo que el formato Horizontal se convierta en...","og_url":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/","og_site_name":"VENALINK","article_published_time":"2023-12-14T04:23:00+00:00","author":"VENALINK","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"VENALINK"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#article","isPartOf":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/"},"author":{"name":"VENALINK","@id":"https:\/\/www.venalink.es\/#\/schema\/person\/f5cba9db2c02b6d2d5341de2426e5ba4"},"headline":"El SPD Horizontal, un proyecto consolidado","datePublished":"2023-12-14T04:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/"},"wordCount":6,"commentCount":0,"image":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.venalink.es\/wp-content\/uploads\/2023\/12\/2023-12-14-Horizontal.jpg","articleSection":["Doing Good By Doing Well"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/","url":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/","name":"El SPD Horizontal, un proyecto consolidado - VENALINK","isPartOf":{"@id":"https:\/\/www.venalink.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#primaryimage"},"image":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.venalink.es\/wp-content\/uploads\/2023\/12\/2023-12-14-Horizontal.jpg","datePublished":"2023-12-14T04:23:00+00:00","author":{"@id":"https:\/\/www.venalink.es\/#\/schema\/person\/f5cba9db2c02b6d2d5341de2426e5ba4"},"breadcrumb":{"@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#primaryimage","url":"https:\/\/www.venalink.es\/wp-content\/uploads\/2023\/12\/2023-12-14-Horizontal.jpg","contentUrl":"https:\/\/www.venalink.es\/wp-content\/uploads\/2023\/12\/2023-12-14-Horizontal.jpg","width":2560,"height":1659,"caption":"spd horizontal proyecto consolidado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.venalink.es\/ca\/spd-horizontal-proyecto-consolidado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.venalink.es\/ca\/"},{"@type":"ListItem","position":2,"name":"El SPD Horizontal, un proyecto consolidado"}]},{"@type":"WebSite","@id":"https:\/\/www.venalink.es\/#website","url":"https:\/\/www.venalink.es\/","name":"VENALINK","description":"Medication Made Simple","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.venalink.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/www.venalink.es\/#\/schema\/person\/f5cba9db2c02b6d2d5341de2426e5ba4","name":"VENALINK","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/b685b6777e4a5e471ef69ef82eb93788357a1e74314713d25a10e3c88d46778c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b685b6777e4a5e471ef69ef82eb93788357a1e74314713d25a10e3c88d46778c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b685b6777e4a5e471ef69ef82eb93788357a1e74314713d25a10e3c88d46778c?s=96&d=blank&r=g","caption":"VENALINK"},"url":"https:\/\/www.venalink.es\/ca\/author\/vse4b64bas2816rnadc5s\/"}]}},"_links":{"self":[{"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/posts\/17422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/comments?post=17422"}],"version-history":[{"count":0,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/posts\/17422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/media\/17366"}],"wp:attachment":[{"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/media?parent=17422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/categories?post=17422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.venalink.es\/ca\/wp-json\/wp\/v2\/tags?post=17422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}